{"id":135,"date":"2021-06-18T18:01:42","date_gmt":"2021-06-18T21:01:42","guid":{"rendered":"https:\/\/clubdelseguro.com.ar\/sitio\/?page_id=135"},"modified":"2021-08-04T21:00:42","modified_gmt":"2021-08-05T00:00:42","slug":"pagos","status":"publish","type":"page","link":"https:\/\/clubdelseguro.com.ar\/sitio\/pagos\/","title":{"rendered":"pagos"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.9.10&#8243; _module_preset=\u00bbdefault\u00bb][et_pb_row _builder_version=\u00bb4.9.10&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.9.10&#8243; _module_preset=\u00bbdefault\u00bb][et_pb_code _builder_version=\u00bb4.9.10&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-138\"><form id=\"wpforms-form-138\" class=\"wpforms-validate wpforms-form\" data-formid=\"138\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/sitio\/wp-json\/wp\/v2\/pages\/135\" data-token=\"fdffb2662e8114bf5655db31dffe0d75\" data-token-time=\"1784130222\"><noscript class=\"wpforms-error-noscript\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-138-field_4-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"4\"><label class=\"wpforms-field-label\">Apellido y Nombre <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-138-field_4\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][4][first]\" required><label for=\"wpforms-138-field_4\" class=\"wpforms-field-sublabel after\">Nombre<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-138-field_4-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][4][last]\" required><label for=\"wpforms-138-field_4-last\" class=\"wpforms-field-sublabel after\">Apellidos<\/label><\/div><\/div><\/div><div id=\"wpforms-138-field_5-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-138-field_5\">Correo electr\u00f3nico <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-138-field_5\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][5]\" spellcheck=\"false\" required><\/div><div id=\"wpforms-138-field_11-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"11\"><label class=\"wpforms-field-label\" for=\"wpforms-138-field_11\">Patente<\/label><input type=\"text\" id=\"wpforms-138-field_11\" class=\"wpforms-field-small\" name=\"wpforms[fields][11]\" ><\/div><div id=\"wpforms-138-field_10-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"10\"><label class=\"wpforms-field-label\" for=\"wpforms-138-field_10\">Celular <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"number\" id=\"wpforms-138-field_10\" class=\"wpforms-field-small wpforms-field-required\" name=\"wpforms[fields][10]\" step=\"any\" required><\/div><div id=\"wpforms-138-field_8-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"8\"><label class=\"wpforms-field-label\" for=\"wpforms-138-field_8\">Informar un Pago o Solicitar un Cobro<\/label><input type=\"text\" id=\"wpforms-138-field_8\" class=\"wpforms-field-large\" name=\"wpforms[fields][8]\" ><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"138\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/clubdelseguro.com.ar\/sitio\/wp-json\/wp\/v2\/pages\/135\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-138\" class=\"wpforms-submit\" data-alt-text=\"Enviando...\" data-submit-text=\"Enviar\" aria-live=\"assertive\" value=\"wpforms-submit\">Enviar<\/button><\/div><\/form><\/div>  <!-- .wpforms-container -->\t[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-138\"><form id=\"wpforms-form-138\" class=\"wpforms-validate wpforms-form\" data-formid=\"138\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/sitio\/wp-json\/wp\/v2\/pages\/135\" data-token=\"fdffb2662e8114bf5655db31dffe0d75\" data-token-time=\"1784130223\"><noscript class=\"wpforms-error-noscript\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-138-field_4-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"4\"><label class=\"wpforms-field-label\">Apellido y Nombre <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-138-field_4\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][4][first]\" required><label for=\"wpforms-138-field_4\" class=\"wpforms-field-sublabel after\">Nombre<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-138-field_4-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][4][last]\" required><label for=\"wpforms-138-field_4-last\" class=\"wpforms-field-sublabel after\">Apellidos<\/label><\/div><\/div><\/div><div id=\"wpforms-138-field_5-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-138-field_5\">Correo electr\u00f3nico <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-138-field_5\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][5]\" spellcheck=\"false\" required><\/div><div id=\"wpforms-138-field_11-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"11\"><label class=\"wpforms-field-label\" for=\"wpforms-138-field_11\">Patente<\/label><input type=\"text\" id=\"wpforms-138-field_11\" class=\"wpforms-field-small\" name=\"wpforms[fields][11]\" ><\/div><div id=\"wpforms-138-field_10-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"10\"><label class=\"wpforms-field-label\" for=\"wpforms-138-field_10\">Celular <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"number\" id=\"wpforms-138-field_10\" class=\"wpforms-field-small wpforms-field-required\" name=\"wpforms[fields][10]\" step=\"any\" required><\/div><div id=\"wpforms-138-field_8-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"8\"><label class=\"wpforms-field-label\" for=\"wpforms-138-field_8\">Informar un Pago o Solicitar un Cobro<\/label><input type=\"text\" id=\"wpforms-138-field_8\" class=\"wpforms-field-large\" name=\"wpforms[fields][8]\" ><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"138\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/clubdelseguro.com.ar\/sitio\/wp-json\/wp\/v2\/pages\/135\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-138\" class=\"wpforms-submit\" data-alt-text=\"Enviando...\" data-submit-text=\"Enviar\" aria-live=\"assertive\" value=\"wpforms-submit\">Enviar<\/button><\/div><\/form><\/div>  <!-- .wpforms-container -->\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_joinchat":[],"footnotes":""},"class_list":["post-135","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/clubdelseguro.com.ar\/sitio\/wp-json\/wp\/v2\/pages\/135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clubdelseguro.com.ar\/sitio\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/clubdelseguro.com.ar\/sitio\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/clubdelseguro.com.ar\/sitio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/clubdelseguro.com.ar\/sitio\/wp-json\/wp\/v2\/comments?post=135"}],"version-history":[{"count":6,"href":"https:\/\/clubdelseguro.com.ar\/sitio\/wp-json\/wp\/v2\/pages\/135\/revisions"}],"predecessor-version":[{"id":166,"href":"https:\/\/clubdelseguro.com.ar\/sitio\/wp-json\/wp\/v2\/pages\/135\/revisions\/166"}],"wp:attachment":[{"href":"https:\/\/clubdelseguro.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}